{"id":81,"date":"2023-03-13T10:20:03","date_gmt":"2023-03-13T10:20:03","guid":{"rendered":"http:\/\/localhost\/wordpress\/?p=3170"},"modified":"2023-08-29T23:19:15","modified_gmt":"2023-08-29T23:19:15","slug":"buro-de-convenciones-de-lima-promperu-y-viva-air-organizan-fam-trip-para-empresas-mice-de-colombia","status":"publish","type":"post","link":"https:\/\/limaconvention.com\/en\/buro-de-convenciones-de-lima-promperu-y-viva-air-organizan-fam-trip-para-empresas-mice-de-colombia\/","title":{"rendered":"Bur\u00f3 de Convenciones de Lima, Promper\u00fa y Viva Air organizan Fam trip para empresas MICE de Colombia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con el objetivo de impulsar el posicionamiento del <strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Per\u00fa\" target=\"_blank\" rel=\"noreferrer noopener\">Per\u00fa<\/a><\/strong> como destino de reuniones, viajes de incentivos y eventos.<br>Representantes de las principales empresas de la industria MICE de <strong>Colombia<\/strong>, llegaron a nuestro pa\u00eds para participar de un viaje de familiarizaci\u00f3n con la finalidad de que obtengan de primera mano una actualizaci\u00f3n experiencial, capacitaci\u00f3n en infraestructura para eventos, congresos y viajes de incentivo y entrenamiento t\u00e9cnico especializado del segmento de reuniones de Per\u00fa, como un destino l\u00edder en los rubros de <em>gastronom\u00eda, cultura, naturaleza e historia<\/em> de alta gama.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las empresas invitadas estuvieron conformadas por:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vaova Travel,<\/li>\n\n\n\n<li>Viajes El Corte Ingl\u00e9s, Nayitur,<\/li>\n\n\n\n<li>Cielos Abiertos,<\/li>\n\n\n\n<li>BCD Travel, CTM en L\u00ednea,<\/li>\n\n\n\n<li>Terra Nova,<\/li>\n\n\n\n<li>Akira Travel<\/li>\n\n\n\n<li>y Aviatur Medell\u00edn.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los invitados estuvieron encantados con la oferta tur\u00edstica de la ciudad de Lima y en la Ciudad imperial de Cuzco. Experiencias como caminatas por el Centro Hist\u00f3rico de Lima, las calles de Barranco (el distrito m\u00e1s art\u00edstico y bohemio de la ciudad), clases de cocteler\u00eda y gastronom\u00eda, el maravilloso viaje a Cuzco y la visita al Santuario Hist\u00f3rico de <strong>Machu Picchu<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento logr\u00f3 con \u00e9xito que los prestadores de servicios tur\u00edsticos de Colombia, incorporen y\/o refuercen en sus planes de comercializaci\u00f3n los atractivos y experiencias de turismo MICE que incluye sectores como naturaleza, cultura, culinaria y diversi\u00f3n que nuestro pa\u00eds ofrece.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe mencionar y agradecer a las empresas asociadas al <strong>Bur\u00f3 de Lima<\/strong> que apoyaron el fam y demostraron excelencia en sus servicios: Be Per\u00fa Boutique Tour Operator, JW Marriot Lima, El Pardo Double Tree by Hilton, Hotel Tambo del Inka, Hotel Palacio del Inka y RLA \u2013 Latam.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de impulsar el posicionamiento del Per\u00fa como destino de reuniones, viajes de incentivos y eventos.Representantes de las principales empresas de la industria MICE de Colombia, llegaron a nuestro pa\u00eds para participar de un viaje de familiarizaci\u00f3n con la finalidad de que obtengan de primera mano una actualizaci\u00f3n experiencial, capacitaci\u00f3n en infraestructura para eventos, congresos y viajes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,45],"tags":[44,24],"class_list":["post-81","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-columna-mas-noticias","tag-empresas","tag-viajes"],"_links":{"self":[{"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/posts\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/comments?post=81"}],"version-history":[{"count":3,"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/posts\/81\/revisions"}],"predecessor-version":[{"id":1323,"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/posts\/81\/revisions\/1323"}],"wp:attachment":[{"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/media?parent=81"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/categories?post=81"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limaconvention.com\/en\/wp-json\/wp\/v2\/tags?post=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}